{"id":33662,"date":"2023-09-29T12:25:47","date_gmt":"2023-09-29T10:25:47","guid":{"rendered":"https:\/\/www.artdanslacite.eu\/?p=33662"},"modified":"2023-09-29T12:26:44","modified_gmt":"2023-09-29T10:26:44","slug":"iris-map-healing-imaginative-journey-for-children","status":"publish","type":"post","link":"https:\/\/www.artdanslacite.eu\/fr\/iris-map-healing-imaginative-journey-for-children\/","title":{"rendered":"Iris Map &#8211; \u00abHealing Imaginative Journey for Children \u00bb"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_custom_heading source=\u00a0\u00bbpost_title\u00a0\u00bb font_container=\u00a0\u00bbtag:h1|text_align:left\u00a0\u00bb use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb][vc_custom_heading text=\u00a0\u00bbUne \u0153uvre multisensorielle bas\u00e9e sur les couleurs. Sept espaces \u00e9nerg\u00e9tiques comme symboles sensoriels et mn\u00e9motechniques \u00a0\u00bb use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb][vc_column_text]Cr\u00e9ation Ann Papoulis \u2013 Production Art dans la Cit\u00e9<\/p>\n<p>2023<\/p>\n<p>Iris Map &#8211; \u00ab Healing Imaginative Journey for Children \u00bb est une \u0153uvre qui propose sept courts-m\u00e9trages qui feront partie des contenus contemplatifs d&rsquo;Illuminart. Ces films permettront aux enfants de changer d&rsquo;\u00e9nergie pendant leur s\u00e9jour \u00e0 l&rsquo;h\u00f4pital, en fonction de leurs besoins \u00e9motionnels. A partir d&rsquo;un menu d&rsquo;options, ils pourront choisir le type d&rsquo;\u00e9nergie qu&rsquo;ils ont envie d&rsquo;explorer[\/vc_column_text][vc_column_text]Le projet<\/p>\n<p>Chaque film emm\u00e8nera les enfants dans un court voyage au gr\u00e9 de leur imagination, afin de soulager leur stress et de leur permettre de ressentir une vibration \u00e0 l&rsquo;int\u00e9rieur de leur \u00eatre. Durant les ateliers, l\u2019artiste a conduit les enfants dans des voyages sensoriels, \u00e0 l&rsquo;aide de films, de sons, d&rsquo;ambiances et d&rsquo;images destin\u00e9s \u00e0 \u00e9veiller les \u00e9nergies de l&rsquo;imagination.<\/p>\n<p>Ils ont dans\u00e9, cr\u00e9\u00e9 des images, chant\u00e9 et racont\u00e9 des histoires sur les th\u00e8mes du myst\u00e8re, la paix, le jeu, l&rsquo;action, la nature, l&rsquo;\u00e9merveillement, l&rsquo;inspiration.<\/p>\n<p>Le mat\u00e9riel g\u00e9n\u00e9r\u00e9 par les enfants &#8211; leurs dessins, leurs histoires, leurs mouvements film\u00e9s \u2013 sont int\u00e9gr\u00e9s dans l\u2019\u0153uvre de l\u2019artiste, pour cr\u00e9er ces sept courts m\u00e9trages qui font partie de cette nouvelle application[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_custom_heading source=\u00a0\u00bbpost_title\u00a0\u00bb font_container=\u00a0\u00bbtag:h1|text_align:left\u00a0\u00bb use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb][vc_custom_heading text=\u00a0\u00bbUne \u0153uvre multisensorielle bas\u00e9e sur les couleurs. Sept espaces \u00e9nerg\u00e9tiques comme symboles sensoriels et mn\u00e9motechniques \u00a0\u00bb use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb][vc_column_text]Cr\u00e9ation Ann Papoulis \u2013 Production Art dans la Cit\u00e9 2023 Iris Map &#8211; \u00ab Healing Imaginative Journey for Children \u00bb<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":6,"featured_media":33628,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[100,35],"tags":[],"class_list":["post-33662","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-illuminart","category-realisations"],"_links":{"self":[{"href":"https:\/\/www.artdanslacite.eu\/fr\/wp-json\/wp\/v2\/posts\/33662","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.artdanslacite.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.artdanslacite.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.artdanslacite.eu\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.artdanslacite.eu\/fr\/wp-json\/wp\/v2\/comments?post=33662"}],"version-history":[{"count":2,"href":"https:\/\/www.artdanslacite.eu\/fr\/wp-json\/wp\/v2\/posts\/33662\/revisions"}],"predecessor-version":[{"id":33664,"href":"https:\/\/www.artdanslacite.eu\/fr\/wp-json\/wp\/v2\/posts\/33662\/revisions\/33664"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.artdanslacite.eu\/fr\/wp-json\/wp\/v2\/media\/33628"}],"wp:attachment":[{"href":"https:\/\/www.artdanslacite.eu\/fr\/wp-json\/wp\/v2\/media?parent=33662"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.artdanslacite.eu\/fr\/wp-json\/wp\/v2\/categories?post=33662"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.artdanslacite.eu\/fr\/wp-json\/wp\/v2\/tags?post=33662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}